{"id":43723,"date":"2025-05-17T09:40:34","date_gmt":"2025-05-17T06:40:34","guid":{"rendered":"https:\/\/sakt.ee\/product\/sip40-ce20-inductive-sensor-10-55dc-pnp-no-nc-20mm-2m-cable\/"},"modified":"2025-11-04T11:38:22","modified_gmt":"2025-11-04T08:38:22","slug":"sip40-ce20-inductive-sensor-10-55dc-pnp-no-nc-20mm-2m-cable","status":"publish","type":"product","link":"https:\/\/sakt.ee\/en\/pood\/process-sensors\/inductive-sensors\/sip40-ce20-inductive-sensor-10-55dc-pnp-no-nc-20mm-2m-cable\/","title":{"rendered":"SIP40-CE20 inductive sensor; 10-55DC; PNP; NO\/NC; 20mm; 2m cable"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":32899,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[3292],"product_tag":[],"manufacturers":[7815],"class_list":{"0":"post-43723","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-inductive-sensors","7":"pa_kaitseklass-ip65-en","8":"pa_kontakt-1-no-1-nc-en","9":"pa_korpus-plastics","10":"pa_laius-40mm-en","11":"pa_mootepiirkond-0-20mm-en","12":"pa_pikkus-113mm-en","13":"pa_toide-10-55v-dc-en","14":"pa_tootemperatuur-25-70c-en","15":"pa_tootja-aeco","16":"pa_uhendustuup-2m-cable","17":"pa_valjund-pnp-en","18":"manufacturers-aeco-en","20":"first","21":"instock","22":"taxable","23":"shipping-taxable","24":"purchasable","25":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.4 (Yoast SEO v25.4) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SIP40-CE20 inductive sensor; 10-55DC; PNP; NO\/NC; 20mm; 2m cable - Sakala T\u00f6\u00f6stusautomaatika O\u00dc<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sakt.ee\/en\/pood\/process-sensors\/inductive-sensors\/sip40-ce20-inductive-sensor-10-55dc-pnp-no-nc-20mm-2m-cable\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SIP40-CE20 inductive sensor; 10-55DC; PNP; NO\/NC; 20mm; 2m cable\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sakt.ee\/en\/pood\/process-sensors\/inductive-sensors\/sip40-ce20-inductive-sensor-10-55dc-pnp-no-nc-20mm-2m-cable\/\" \/>\n<meta property=\"og:site_name\" content=\"Sakala T\u00f6\u00f6stusautomaatika O\u00dc\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-04T08:38:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sakt.ee\/wp-content\/uploads\/2025\/05\/5823.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"593\" \/>\n\t<meta property=\"og:image:height\" content=\"294\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"58,90&euro; +VAT\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sakt.ee\/en\/pood\/process-sensors\/inductive-sensors\/sip40-ce20-inductive-sensor-10-55dc-pnp-no-nc-20mm-2m-cable\/\",\"url\":\"https:\/\/sakt.ee\/en\/pood\/process-sensors\/inductive-sensors\/sip40-ce20-inductive-sensor-10-55dc-pnp-no-nc-20mm-2m-cable\/\",\"name\":\"SIP40-CE20 inductive sensor; 10-55DC; PNP; NO\/NC; 20mm; 2m cable - Sakala T\u00f6\u00f6stusautomaatika O\u00dc\",\"isPartOf\":{\"@id\":\"https:\/\/sakt.ee\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sakt.ee\/en\/pood\/process-sensors\/inductive-sensors\/sip40-ce20-inductive-sensor-10-55dc-pnp-no-nc-20mm-2m-cable\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sakt.ee\/en\/pood\/process-sensors\/inductive-sensors\/sip40-ce20-inductive-sensor-10-55dc-pnp-no-nc-20mm-2m-cable\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sakt.ee\/wp-content\/uploads\/2025\/05\/5823.jpg\",\"datePublished\":\"2025-05-17T06:40:34+00:00\",\"dateModified\":\"2025-11-04T08:38:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sakt.ee\/en\/pood\/process-sensors\/inductive-sensors\/sip40-ce20-inductive-sensor-10-55dc-pnp-no-nc-20mm-2m-cable\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sakt.ee\/en\/pood\/process-sensors\/inductive-sensors\/sip40-ce20-inductive-sensor-10-55dc-pnp-no-nc-20mm-2m-cable\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/sakt.ee\/en\/pood\/process-sensors\/inductive-sensors\/sip40-ce20-inductive-sensor-10-55dc-pnp-no-nc-20mm-2m-cable\/#primaryimage\",\"url\":\"https:\/\/sakt.ee\/wp-content\/uploads\/2025\/05\/5823.jpg\",\"contentUrl\":\"https:\/\/sakt.ee\/wp-content\/uploads\/2025\/05\/5823.jpg\",\"width\":593,\"height\":294},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sakt.ee\/en\/pood\/process-sensors\/inductive-sensors\/sip40-ce20-inductive-sensor-10-55dc-pnp-no-nc-20mm-2m-cable\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/sakt.ee\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/sakt.ee\/en\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SIP40-CE20 inductive sensor; 10-55DC; PNP; NO\/NC; 20mm; 2m cable\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sakt.ee\/en\/#website\",\"url\":\"https:\/\/sakt.ee\/en\/\",\"name\":\"Sakala T\u00f6\u00f6stusautomaatika O\u00dc\",\"description\":\"T\u00f6\u00f6stusautomaatika e-pood\",\"publisher\":{\"@id\":\"https:\/\/sakt.ee\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sakt.ee\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sakt.ee\/en\/#organization\",\"name\":\"Sakala T\u00f6\u00f6stusautomaatika O\u00dc\",\"url\":\"https:\/\/sakt.ee\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/sakt.ee\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sakt.ee\/wp-content\/uploads\/2025\/05\/Sakala-Toostusautomaatika-favicon.png\",\"contentUrl\":\"https:\/\/sakt.ee\/wp-content\/uploads\/2025\/05\/Sakala-Toostusautomaatika-favicon.png\",\"width\":500,\"height\":500,\"caption\":\"Sakala T\u00f6\u00f6stusautomaatika O\u00dc\"},\"image\":{\"@id\":\"https:\/\/sakt.ee\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"58.90\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"SIP000103\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"SIP40-CE20 inductive sensor; 10-55DC; PNP; NO\/NC; 20mm; 2m cable - Sakala T\u00f6\u00f6stusautomaatika O\u00dc","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sakt.ee\/en\/pood\/process-sensors\/inductive-sensors\/sip40-ce20-inductive-sensor-10-55dc-pnp-no-nc-20mm-2m-cable\/","og_locale":"en_US","og_type":"article","og_title":"SIP40-CE20 inductive sensor; 10-55DC; PNP; NO\/NC; 20mm; 2m cable","og_url":"https:\/\/sakt.ee\/en\/pood\/process-sensors\/inductive-sensors\/sip40-ce20-inductive-sensor-10-55dc-pnp-no-nc-20mm-2m-cable\/","og_site_name":"Sakala T\u00f6\u00f6stusautomaatika O\u00dc","article_modified_time":"2025-11-04T08:38:22+00:00","og_image":[{"width":593,"height":294,"url":"https:\/\/sakt.ee\/wp-content\/uploads\/2025\/05\/5823.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"58,90&euro; +VAT","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sakt.ee\/en\/pood\/process-sensors\/inductive-sensors\/sip40-ce20-inductive-sensor-10-55dc-pnp-no-nc-20mm-2m-cable\/","url":"https:\/\/sakt.ee\/en\/pood\/process-sensors\/inductive-sensors\/sip40-ce20-inductive-sensor-10-55dc-pnp-no-nc-20mm-2m-cable\/","name":"SIP40-CE20 inductive sensor; 10-55DC; PNP; NO\/NC; 20mm; 2m cable - Sakala T\u00f6\u00f6stusautomaatika O\u00dc","isPartOf":{"@id":"https:\/\/sakt.ee\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sakt.ee\/en\/pood\/process-sensors\/inductive-sensors\/sip40-ce20-inductive-sensor-10-55dc-pnp-no-nc-20mm-2m-cable\/#primaryimage"},"image":{"@id":"https:\/\/sakt.ee\/en\/pood\/process-sensors\/inductive-sensors\/sip40-ce20-inductive-sensor-10-55dc-pnp-no-nc-20mm-2m-cable\/#primaryimage"},"thumbnailUrl":"https:\/\/sakt.ee\/wp-content\/uploads\/2025\/05\/5823.jpg","datePublished":"2025-05-17T06:40:34+00:00","dateModified":"2025-11-04T08:38:22+00:00","breadcrumb":{"@id":"https:\/\/sakt.ee\/en\/pood\/process-sensors\/inductive-sensors\/sip40-ce20-inductive-sensor-10-55dc-pnp-no-nc-20mm-2m-cable\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sakt.ee\/en\/pood\/process-sensors\/inductive-sensors\/sip40-ce20-inductive-sensor-10-55dc-pnp-no-nc-20mm-2m-cable\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sakt.ee\/en\/pood\/process-sensors\/inductive-sensors\/sip40-ce20-inductive-sensor-10-55dc-pnp-no-nc-20mm-2m-cable\/#primaryimage","url":"https:\/\/sakt.ee\/wp-content\/uploads\/2025\/05\/5823.jpg","contentUrl":"https:\/\/sakt.ee\/wp-content\/uploads\/2025\/05\/5823.jpg","width":593,"height":294},{"@type":"BreadcrumbList","@id":"https:\/\/sakt.ee\/en\/pood\/process-sensors\/inductive-sensors\/sip40-ce20-inductive-sensor-10-55dc-pnp-no-nc-20mm-2m-cable\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sakt.ee\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/sakt.ee\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"SIP40-CE20 inductive sensor; 10-55DC; PNP; NO\/NC; 20mm; 2m cable"}]},{"@type":"WebSite","@id":"https:\/\/sakt.ee\/en\/#website","url":"https:\/\/sakt.ee\/en\/","name":"Sakala T\u00f6\u00f6stusautomaatika O\u00dc","description":"T\u00f6\u00f6stusautomaatika e-pood","publisher":{"@id":"https:\/\/sakt.ee\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sakt.ee\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/sakt.ee\/en\/#organization","name":"Sakala T\u00f6\u00f6stusautomaatika O\u00dc","url":"https:\/\/sakt.ee\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sakt.ee\/en\/#\/schema\/logo\/image\/","url":"https:\/\/sakt.ee\/wp-content\/uploads\/2025\/05\/Sakala-Toostusautomaatika-favicon.png","contentUrl":"https:\/\/sakt.ee\/wp-content\/uploads\/2025\/05\/Sakala-Toostusautomaatika-favicon.png","width":500,"height":500,"caption":"Sakala T\u00f6\u00f6stusautomaatika O\u00dc"},"image":{"@id":"https:\/\/sakt.ee\/en\/#\/schema\/logo\/image\/"}}]},"product_price_amount":"58.90","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"SIP000103","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/sakt.ee\/en\/wp-json\/wp\/v2\/product\/43723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sakt.ee\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sakt.ee\/en\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/sakt.ee\/en\/wp-json\/wp\/v2\/product\/43723\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sakt.ee\/en\/wp-json\/wp\/v2\/media\/32899"}],"wp:attachment":[{"href":"https:\/\/sakt.ee\/en\/wp-json\/wp\/v2\/media?parent=43723"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/sakt.ee\/en\/wp-json\/wp\/v2\/product_brand?post=43723"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sakt.ee\/en\/wp-json\/wp\/v2\/product_cat?post=43723"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sakt.ee\/en\/wp-json\/wp\/v2\/product_tag?post=43723"},{"taxonomy":"manufacturers","embeddable":true,"href":"https:\/\/sakt.ee\/en\/wp-json\/wp\/v2\/manufacturers?post=43723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}